{"id":1897,"date":"2023-05-02T11:09:49","date_gmt":"2023-05-02T09:09:49","guid":{"rendered":"https:\/\/blog.phzh.ch\/bibliothek\/?p=1897"},"modified":"2024-08-06T12:36:36","modified_gmt":"2024-08-06T10:36:36","slug":"willkommen-im-neuen-online-katalog","status":"publish","type":"post","link":"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/","title":{"rendered":"Willkommen im neuen Online-Katalog!"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Neuer-Online-Katalog-1024x683.jpg\" alt=\"\" class=\"wp-image-1902\" style=\"width:668px;height:445px\" srcset=\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Neuer-Online-Katalog-1024x683.jpg 1024w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Neuer-Online-Katalog-300x200.jpg 300w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Neuer-Online-Katalog-768x512.jpg 768w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Neuer-Online-Katalog-1536x1024.jpg 1536w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Neuer-Online-Katalog-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Im Online-Katalog sind s\u00e4mtliche Medien der Bibliothek der PH Z\u00fcrich verzeichnet. In den letzten Monaten wurde die Nutzungsoberfl\u00e4che \u00fcberarbeitet. Damit soll insbesondere der Zugang zur digitalen Bibliothek erleichtert werden.<\/strong><\/p>\n\n\n\n<p>Die Nutzenden profitieren auf verschiedene Weise von der neuen <a href=\"https:\/\/slsp-zph.primo.exlibrisgroup.com\/discovery\/search?vid=41SLSP_PHZ:PHZH&amp;lang=de\" target=\"_blank\" rel=\"noreferrer noopener\">View<\/a> (Oberfl\u00e4che), die ab Mai 2023 zug\u00e4nglich ist. Ins Auge fallen vor allem die ansprechenden <a href=\"https:\/\/slsp-zph.primo.exlibrisgroup.com\/discovery\/collectionDiscovery?vid=41SLSP_PHZ%3APHZH&amp;collectionId=8156207460005521\" target=\"_blank\" rel=\"noreferrer noopener\">Sammlungen<\/a>. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"481\" src=\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Sammlungen-1024x481.jpg\" alt=\"\" class=\"wp-image-1911\" srcset=\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Sammlungen-1024x481.jpg 1024w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Sammlungen-300x141.jpg 300w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Sammlungen-768x361.jpg 768w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Sammlungen-1536x722.jpg 1536w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Sammlungen-2048x963.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Damit  ist ein \u00dcberblick \u00fcber s\u00e4mtliche lizenzierten digitalen Medien wie E-Books, E-Journals, Streamingfilme und Datenbanken m\u00f6glich \u2013 erstmals k\u00f6nnen Interessierte im digitalen Bestand \u00abschm\u00f6kern\u00bb, ohne direkt eine Suche absetzen zu m\u00fcssen. Das ist insbesondere dann n\u00fctzlich, wenn man noch kein Thema oder keinen Suchbegriff zur Hand hat und dennoch wissen will, was die digitale Bibliothek so bietet. <\/p>\n\n\n\n<p>Vollzugriff erh\u00e4lt man wie bisher via <a href=\"https:\/\/phzh.ch\/dienstleistungen\/alle-dienstleistungen-auf-einen-blick\/internetzugang-wlan\/\" target=\"_blank\" rel=\"noreferrer noopener\">WLAN vor Ort<\/a> oder <a href=\"https:\/\/phzh.sharepoint.com\/sites\/yoda\/Seiten\/Alle\/VPN-Hauptseite.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">Virtual Private Network der PH Z\u00fcrich<\/a>. Alle lizenzierten Medien sind kostenlos nutzbar.<\/p>\n\n\n\n<p><strong>Auch die Suche wurde angepasst<\/strong><\/p>\n\n\n\n<p>M\u00f6chte man dennoch suchbasiert vorgehen, stehen weiterhin die <a href=\"https:\/\/slsp-zph.primo.exlibrisgroup.com\/discovery\/search?vid=41SLSP_PHZ:PHZH&amp;lang=de\" target=\"_blank\" rel=\"noreferrer noopener\">Hauptsuche<\/a> sowie ab sofort ein <a href=\"https:\/\/slsp-zph.primo.exlibrisgroup.com\/discovery\/jsearch?vid=41SLSP_PHZ%3APHZH\" target=\"_blank\" rel=\"noreferrer noopener\">Zeitschriftenindex<\/a> zur Verf\u00fcgung. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"449\" src=\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Hauptsuche-1024x449.jpg\" alt=\"\" class=\"wp-image-1905\" srcset=\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Hauptsuche-1024x449.jpg 1024w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Hauptsuche-300x132.jpg 300w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Hauptsuche-768x337.jpg 768w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Hauptsuche-1536x673.jpg 1536w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Hauptsuche.jpg 1916w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Die Hauptsuche ist neu standardm\u00e4ssig auf die Medien der PH Z\u00fcrich eingeschr\u00e4nkt. Nach wie vor lassen sich mit dem Suchprofil \u00abswisscovery\u00bb die Best\u00e4nde von 490 wissenschaftlichen Bibliotheken in der Schweiz erkunden. Ausserdem sind <a href=\"https:\/\/blog.phzh.ch\/bibliothek\/2021\/08\/20\/diese-vorteile-bringt-ihnen-das-neue-bibliothekssystem\/\" target=\"_blank\" rel=\"noreferrer noopener\">seit 2021 modulspezifische Literaturlisten (Seminarapparate) direkt \u00fcber den Online-Katalog auffindbar<\/a>. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"311\" src=\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Zeitschriftensuche-1-1024x311.jpg\" alt=\"\" class=\"wp-image-1907\" srcset=\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Zeitschriftensuche-1-1024x311.jpg 1024w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Zeitschriftensuche-1-300x91.jpg 300w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Zeitschriftensuche-1-768x233.jpg 768w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Zeitschriftensuche-1-1536x466.jpg 1536w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Zeitschriftensuche-1.jpg 1704w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Der Zeitschriftenindex zeigt gezielt physische und digitale Zeitschriften aus dem Bibliotheksbestand an. F\u00fcr die Suche nach einzelnen digitalen Zeitschriften<em>artikeln<\/em> stehen weiterhin die Datenbanken und\/oder die Portale der Zeitschriftenanbieter zur Verf\u00fcgung. Sie erscheinen nach Themen geordnet in den <a href=\"https:\/\/slsp-zph.primo.exlibrisgroup.com\/discovery\/collectionDiscovery?vid=41SLSP_PHZ%3APHZH&amp;collectionId=8148287480005521\" target=\"_blank\" rel=\"noreferrer noopener\">Sammlungen<\/a>. Erg\u00e4nzt werden sie um zahlreiche offene <em>Artikel<\/em> in der <a href=\"https:\/\/slsp-zph.primo.exlibrisgroup.com\/discovery\/search?vid=41SLSP_PHZ:PHZH&amp;lang=de\" target=\"_blank\" rel=\"noreferrer noopener\">Hauptsuche<\/a> (Publikationsstandard Open Access).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"450\" src=\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Anbieterplattformen-1024x450.jpg\" alt=\"\" class=\"wp-image-1909\" srcset=\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Anbieterplattformen-1024x450.jpg 1024w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Anbieterplattformen-300x132.jpg 300w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Anbieterplattformen-768x338.jpg 768w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Anbieterplattformen-1536x676.jpg 1536w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Anbieterplattformen.jpg 1905w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>F\u00fcr eine Volltextsuche, fr\u00fchere Sichtbarkeit neu erworbener Exemplare und eine inhaltsoptimierte Oberfl\u00e4che besucht man fallweise, etwa bei den Film- oder bei den E-Book-Plattformen, am besten die einzelnen Anbieterseiten. Der Beschrieb gibt Auskunft.<\/p>\n\n\n\n<p><strong>Neues Erscheinungsbild \u2013 erhaltene Funktionalit\u00e4t<\/strong><\/p>\n\n\n\n<p>Wie bisher k\u00f6nnen derzeit ausgeliehene Medien im Katalog reserviert und in die automatisierte Abholstation der PH Z\u00fcrich bestellt werden. Weitere Informationen finden sich <a href=\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/20\/medien-selbststaendig-abholen-so-geht-es\/\" target=\"_blank\" rel=\"noreferrer noopener\">hier<\/a>.<\/p>\n\n\n\n<p>Im <a href=\"https:\/\/eduid.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">Konto<\/a> lassen sich Suchen und Favoriten speichern, eigene Ausleihen und Bestellungen verwalten. Die <a href=\"https:\/\/youtube.com\/playlist?list=PL2S8_YX8ADkgxb65GtiK3a_z46F8a0KiW\" target=\"_blank\" rel=\"noreferrer noopener\">Tutorials<\/a> geben Auskunft, wie man den Online-Katalog optimal nutzt (sie werden derzeit aktualisiert: funktionales Vorgehen beh\u00e4lt vielerorts seine G\u00fcltigkeit).<\/p>\n\n\n\n<p>Auch die im Rahmen von Unterrichtsmodulen entstandenen Lernumgebungen zur Lese- und Schreibf\u00f6rderung sind neu in den <a href=\"https:\/\/slsp-zph.primo.exlibrisgroup.com\/discovery\/collectionDiscovery?vid=41SLSP_PHZ%3APHZH&amp;collectionId=8141096200005521\" target=\"_blank\" rel=\"noreferrer noopener\">Sammlungen<\/a> integriert. Die Ausleihbedingungen bleiben die gleichen.<\/p>\n\n\n\n<div class=\"wp-block-group alignfull has-yellow-gradient-gradient-background has-text-color has-background\" style=\"color:#000000\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div style=\"height:64px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\" style=\"line-height:.9\"><strong>Online-Katalog<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"schedule-a-visit\" style=\"font-size:59px;line-height:1.15\">Jetzt neue View besuchen<\/h2>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50\"><a class=\"wp-block-button__link has-bright-blue-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/slsp-zph.primo.exlibrisgroup.com\/discovery\/search?vid=41SLSP_PHZ:PHZH\" style=\"border-radius:50px;color:#ffffff\" target=\"_blank\" rel=\"noreferrer noopener\">Hier klicken<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:64px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Online-Katalog sind s\u00e4mtliche Medien der Bibliothek der PH Z\u00fcrich verzeichnet. In den letzten Monaten wurde die Nutzungsoberfl\u00e4che \u00fcberarbeitet. Damit soll insbesondere der Zugang zur digitalen Bibliothek erleichtert werden. Die Nutzenden profitieren auf verschiedene Weise von der neuen View (Oberfl\u00e4che), die ab Mai 2023 zug\u00e4nglich ist. Ins Auge fallen vor allem die ansprechenden Sammlungen. Damit &hellip; <a href=\"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/\" class=\"more-link\"><span class=\"screen-reader-text\">Willkommen im neuen Online-Katalog!<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1414,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_s2mail":"yes","footnotes":""},"categories":[39],"tags":[],"class_list":["post-1897","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Willkommen im neuen Online-Katalog! - biblioPHil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Willkommen im neuen Online-Katalog! - biblioPHil\" \/>\n<meta property=\"og:description\" content=\"Im Online-Katalog sind s\u00e4mtliche Medien der Bibliothek der PH Z\u00fcrich verzeichnet. In den letzten Monaten wurde die Nutzungsoberfl\u00e4che \u00fcberarbeitet. Damit soll insbesondere der Zugang zur digitalen Bibliothek erleichtert werden. Die Nutzenden profitieren auf verschiedene Weise von der neuen View (Oberfl\u00e4che), die ab Mai 2023 zug\u00e4nglich ist. Ins Auge fallen vor allem die ansprechenden Sammlungen. Damit &hellip; Willkommen im neuen Online-Katalog! weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/\" \/>\n<meta property=\"og:site_name\" content=\"biblioPHil\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-02T09:09:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-06T10:36:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Neuer-Online-Katalog-1024x683.jpg\" \/>\n<meta name=\"author\" content=\"andreasgrossmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"andreasgrossmann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/\"},\"author\":{\"name\":\"andreasgrossmann\",\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/#\/schema\/person\/4360211b9221fbb6cef4a29576ba41f5\"},\"headline\":\"Willkommen im neuen Online-Katalog!\",\"datePublished\":\"2023-05-02T09:09:49+00:00\",\"dateModified\":\"2024-08-06T10:36:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/\"},\"wordCount\":403,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Neuer-Online-Katalog-1024x683.jpg\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/\",\"url\":\"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/\",\"name\":\"Willkommen im neuen Online-Katalog! - biblioPHil\",\"isPartOf\":{\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Neuer-Online-Katalog-1024x683.jpg\",\"datePublished\":\"2023-05-02T09:09:49+00:00\",\"dateModified\":\"2024-08-06T10:36:36+00:00\",\"author\":{\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/#\/schema\/person\/4360211b9221fbb6cef4a29576ba41f5\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/#primaryimage\",\"url\":\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Neuer-Online-Katalog-scaled.jpg\",\"contentUrl\":\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Neuer-Online-Katalog-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.phzh.ch\/bibliothek\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Willkommen im neuen Online-Katalog!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/#website\",\"url\":\"https:\/\/blog.phzh.ch\/bibliothek\/\",\"name\":\"biblioPHil\",\"description\":\"Blog der Bibliothek der PH Z\u00fcrich\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.phzh.ch\/bibliothek\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/#\/schema\/person\/4360211b9221fbb6cef4a29576ba41f5\",\"name\":\"andreasgrossmann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/05012106f8bf05a68e1ecc068b8fbee4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/05012106f8bf05a68e1ecc068b8fbee4?s=96&d=mm&r=g\",\"caption\":\"andreasgrossmann\"},\"url\":\"https:\/\/blog.phzh.ch\/bibliothek\/author\/andreasgrossmann\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Willkommen im neuen Online-Katalog! - biblioPHil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/","og_locale":"de_DE","og_type":"article","og_title":"Willkommen im neuen Online-Katalog! - biblioPHil","og_description":"Im Online-Katalog sind s\u00e4mtliche Medien der Bibliothek der PH Z\u00fcrich verzeichnet. In den letzten Monaten wurde die Nutzungsoberfl\u00e4che \u00fcberarbeitet. Damit soll insbesondere der Zugang zur digitalen Bibliothek erleichtert werden. Die Nutzenden profitieren auf verschiedene Weise von der neuen View (Oberfl\u00e4che), die ab Mai 2023 zug\u00e4nglich ist. Ins Auge fallen vor allem die ansprechenden Sammlungen. Damit &hellip; Willkommen im neuen Online-Katalog! weiterlesen","og_url":"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/","og_site_name":"biblioPHil","article_published_time":"2023-05-02T09:09:49+00:00","article_modified_time":"2024-08-06T10:36:36+00:00","og_image":[{"url":"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Neuer-Online-Katalog-1024x683.jpg","type":"","width":"","height":""}],"author":"andreasgrossmann","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"andreasgrossmann","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/#article","isPartOf":{"@id":"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/"},"author":{"name":"andreasgrossmann","@id":"https:\/\/blog.phzh.ch\/bibliothek\/#\/schema\/person\/4360211b9221fbb6cef4a29576ba41f5"},"headline":"Willkommen im neuen Online-Katalog!","datePublished":"2023-05-02T09:09:49+00:00","dateModified":"2024-08-06T10:36:36+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/"},"wordCount":403,"commentCount":0,"image":{"@id":"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Neuer-Online-Katalog-1024x683.jpg","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/","url":"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/","name":"Willkommen im neuen Online-Katalog! - biblioPHil","isPartOf":{"@id":"https:\/\/blog.phzh.ch\/bibliothek\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/#primaryimage"},"image":{"@id":"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Neuer-Online-Katalog-1024x683.jpg","datePublished":"2023-05-02T09:09:49+00:00","dateModified":"2024-08-06T10:36:36+00:00","author":{"@id":"https:\/\/blog.phzh.ch\/bibliothek\/#\/schema\/person\/4360211b9221fbb6cef4a29576ba41f5"},"breadcrumb":{"@id":"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/#primaryimage","url":"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Neuer-Online-Katalog-scaled.jpg","contentUrl":"https:\/\/blog.phzh.ch\/bibliothek\/files\/2023\/04\/Neuer-Online-Katalog-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/blog.phzh.ch\/bibliothek\/2023\/05\/02\/willkommen-im-neuen-online-katalog\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.phzh.ch\/bibliothek\/"},{"@type":"ListItem","position":2,"name":"Willkommen im neuen Online-Katalog!"}]},{"@type":"WebSite","@id":"https:\/\/blog.phzh.ch\/bibliothek\/#website","url":"https:\/\/blog.phzh.ch\/bibliothek\/","name":"biblioPHil","description":"Blog der Bibliothek der PH Z\u00fcrich","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.phzh.ch\/bibliothek\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.phzh.ch\/bibliothek\/#\/schema\/person\/4360211b9221fbb6cef4a29576ba41f5","name":"andreasgrossmann","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.phzh.ch\/bibliothek\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/05012106f8bf05a68e1ecc068b8fbee4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05012106f8bf05a68e1ecc068b8fbee4?s=96&d=mm&r=g","caption":"andreasgrossmann"},"url":"https:\/\/blog.phzh.ch\/bibliothek\/author\/andreasgrossmann\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/posts\/1897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/users\/1414"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/comments?post=1897"}],"version-history":[{"count":18,"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/posts\/1897\/revisions"}],"predecessor-version":[{"id":2266,"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/posts\/1897\/revisions\/2266"}],"wp:attachment":[{"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/media?parent=1897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/categories?post=1897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/tags?post=1897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}