{"id":1552,"date":"2022-05-03T11:28:44","date_gmt":"2022-05-03T09:28:44","guid":{"rendered":"https:\/\/blog.phzh.ch\/bibliothek\/?p=1552"},"modified":"2022-07-29T12:00:14","modified_gmt":"2022-07-29T10:00:14","slug":"lernendenprojekt-mentale-gesundheit-in-der-schule","status":"publish","type":"post","link":"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/","title":{"rendered":"Lernendenprojekt: \u00abMentale Gesundheit in der Schule\u00bb"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/AdobeStock_20199278-lq-1024x683.jpg\" alt=\"\" class=\"wp-image-1553\" width=\"667\" height=\"445\" srcset=\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/AdobeStock_20199278-lq-1024x683.jpg 1024w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/AdobeStock_20199278-lq-300x200.jpg 300w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/AdobeStock_20199278-lq-768x512.jpg 768w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/AdobeStock_20199278-lq-1536x1024.jpg 1536w, https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/AdobeStock_20199278-lq-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/figure>\n\n\n\n<p><strong>Die neue Medienausstellung der Bibliothek zum Thema \u00abMentale Gesundheit in der Schule\u00bb ist der erfolgreiche Abschluss eines Lernendenprojekts. Vom 3. bis 6. Mai werden im Stockwerk G bei der Theke spannende Medientipps pr\u00e4sentiert. Vorbeikommen!<\/strong><\/p>\n\n\n\n<p>Das Ziel der Ausstellung ist es, angehende und ausgebildete Lehrpersonen auf das wichtige Thema der mentalen Gesundheit der Sch\u00fclerschaft aufmerksam zu machen. <\/p>\n\n\n\n<p>In der Auswahl der Medientipps wurde versucht, verschiedene Perspektiven der mentalen Notlagen offenzulegen. Niedergeschlagenheit kann sich auf etliche Arten \u00e4ussern und vom klassischen Bild oder gelernten Klischee abweichen. Es werden vielseitige Herangehensweisen aufgezeigt, die Lehrpersonen im Umgang mit solchen Situationen sensibilisieren sollen. Wie kann man empathisch, kreativ und auch einmal ausserhalb ausgetretener Pfade reagieren?<\/p>\n\n\n\n<p>Sind Sie interessiert? Dann kommen Sie doch vorbei und schauen sich die unterschiedlichen Medientipps in physischer und elektronischer Form an!<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile has-light-gray-background-color has-background\" style=\"grid-template-columns:16% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"95\" height=\"119\" src=\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/LD.jpg\" alt=\"\" class=\"wp-image-1559 size-full\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-align-left has-small-font-size\"><em>Das zweimonatige Lernendenprojekt hatte zum Ziel, gelernte Abl\u00e4ufe in Service und Kommunikation zu festigen und anzuwenden (Konzeption, Durchf\u00fchrung, Vermarktung und Auswertung einer eigenen Buchausstellung).<\/em><\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die neue Medienausstellung der Bibliothek zum Thema \u00abMentale Gesundheit in der Schule\u00bb ist der erfolgreiche Abschluss eines Lernendenprojekts. Vom 3. bis 6. Mai werden im Stockwerk G bei der Theke spannende Medientipps pr\u00e4sentiert. Vorbeikommen! Das Ziel der Ausstellung ist es, angehende und ausgebildete Lehrpersonen auf das wichtige Thema der mentalen Gesundheit der Sch\u00fclerschaft aufmerksam zu &hellip; <a href=\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/\" class=\"more-link\"><span class=\"screen-reader-text\">Lernendenprojekt: \u00abMentale Gesundheit in der Schule\u00bb<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1439,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","_s2mail":"yes","footnotes":""},"categories":[39],"tags":[],"class_list":["post-1552","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lernendenprojekt: \u00abMentale Gesundheit in der Schule\u00bb - biblioPHil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lernendenprojekt: \u00abMentale Gesundheit in der Schule\u00bb - biblioPHil\" \/>\n<meta property=\"og:description\" content=\"Die neue Medienausstellung der Bibliothek zum Thema \u00abMentale Gesundheit in der Schule\u00bb ist der erfolgreiche Abschluss eines Lernendenprojekts. Vom 3. bis 6. Mai werden im Stockwerk G bei der Theke spannende Medientipps pr\u00e4sentiert. Vorbeikommen! Das Ziel der Ausstellung ist es, angehende und ausgebildete Lehrpersonen auf das wichtige Thema der mentalen Gesundheit der Sch\u00fclerschaft aufmerksam zu &hellip; Lernendenprojekt: \u00abMentale Gesundheit in der Schule\u00bb weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/\" \/>\n<meta property=\"og:site_name\" content=\"biblioPHil\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-03T09:28:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-29T10:00:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/AdobeStock_20199278-lq-1024x683.jpg\" \/>\n<meta name=\"author\" content=\"laradevesa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"laradevesa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/\"},\"author\":{\"name\":\"laradevesa\",\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/#\/schema\/person\/9ac4db73a0ab3878a7f5b8381dd46a26\"},\"headline\":\"Lernendenprojekt: \u00abMentale Gesundheit in der Schule\u00bb\",\"datePublished\":\"2022-05-03T09:28:44+00:00\",\"dateModified\":\"2022-07-29T10:00:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/\"},\"wordCount\":162,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/AdobeStock_20199278-lq-1024x683.jpg\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/\",\"url\":\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/\",\"name\":\"Lernendenprojekt: \u00abMentale Gesundheit in der Schule\u00bb - biblioPHil\",\"isPartOf\":{\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/AdobeStock_20199278-lq-1024x683.jpg\",\"datePublished\":\"2022-05-03T09:28:44+00:00\",\"dateModified\":\"2022-07-29T10:00:14+00:00\",\"author\":{\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/#\/schema\/person\/9ac4db73a0ab3878a7f5b8381dd46a26\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/#primaryimage\",\"url\":\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/AdobeStock_20199278-lq-1024x683.jpg\",\"contentUrl\":\"https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/AdobeStock_20199278-lq-1024x683.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.phzh.ch\/bibliothek\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lernendenprojekt: \u00abMentale Gesundheit in der Schule\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/#website\",\"url\":\"https:\/\/blog.phzh.ch\/bibliothek\/\",\"name\":\"biblioPHil\",\"description\":\"Blog der Bibliothek der PH Z\u00fcrich\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.phzh.ch\/bibliothek\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/#\/schema\/person\/9ac4db73a0ab3878a7f5b8381dd46a26\",\"name\":\"laradevesa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/blog.phzh.ch\/bibliothek\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/72078c455ba0352ff2c307bcfb259999?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/72078c455ba0352ff2c307bcfb259999?s=96&d=mm&r=g\",\"caption\":\"laradevesa\"},\"url\":\"https:\/\/blog.phzh.ch\/bibliothek\/author\/ldevesa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lernendenprojekt: \u00abMentale Gesundheit in der Schule\u00bb - biblioPHil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/","og_locale":"de_DE","og_type":"article","og_title":"Lernendenprojekt: \u00abMentale Gesundheit in der Schule\u00bb - biblioPHil","og_description":"Die neue Medienausstellung der Bibliothek zum Thema \u00abMentale Gesundheit in der Schule\u00bb ist der erfolgreiche Abschluss eines Lernendenprojekts. Vom 3. bis 6. Mai werden im Stockwerk G bei der Theke spannende Medientipps pr\u00e4sentiert. Vorbeikommen! Das Ziel der Ausstellung ist es, angehende und ausgebildete Lehrpersonen auf das wichtige Thema der mentalen Gesundheit der Sch\u00fclerschaft aufmerksam zu &hellip; Lernendenprojekt: \u00abMentale Gesundheit in der Schule\u00bb weiterlesen","og_url":"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/","og_site_name":"biblioPHil","article_published_time":"2022-05-03T09:28:44+00:00","article_modified_time":"2022-07-29T10:00:14+00:00","og_image":[{"url":"https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/AdobeStock_20199278-lq-1024x683.jpg","type":"","width":"","height":""}],"author":"laradevesa","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"laradevesa","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/#article","isPartOf":{"@id":"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/"},"author":{"name":"laradevesa","@id":"https:\/\/blog.phzh.ch\/bibliothek\/#\/schema\/person\/9ac4db73a0ab3878a7f5b8381dd46a26"},"headline":"Lernendenprojekt: \u00abMentale Gesundheit in der Schule\u00bb","datePublished":"2022-05-03T09:28:44+00:00","dateModified":"2022-07-29T10:00:14+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/"},"wordCount":162,"commentCount":0,"image":{"@id":"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/AdobeStock_20199278-lq-1024x683.jpg","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/","url":"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/","name":"Lernendenprojekt: \u00abMentale Gesundheit in der Schule\u00bb - biblioPHil","isPartOf":{"@id":"https:\/\/blog.phzh.ch\/bibliothek\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/#primaryimage"},"image":{"@id":"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/AdobeStock_20199278-lq-1024x683.jpg","datePublished":"2022-05-03T09:28:44+00:00","dateModified":"2022-07-29T10:00:14+00:00","author":{"@id":"https:\/\/blog.phzh.ch\/bibliothek\/#\/schema\/person\/9ac4db73a0ab3878a7f5b8381dd46a26"},"breadcrumb":{"@id":"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/#primaryimage","url":"https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/AdobeStock_20199278-lq-1024x683.jpg","contentUrl":"https:\/\/blog.phzh.ch\/bibliothek\/files\/2022\/04\/AdobeStock_20199278-lq-1024x683.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.phzh.ch\/bibliothek\/2022\/05\/03\/lernendenprojekt-mentale-gesundheit-in-der-schule\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.phzh.ch\/bibliothek\/"},{"@type":"ListItem","position":2,"name":"Lernendenprojekt: \u00abMentale Gesundheit in der Schule\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/blog.phzh.ch\/bibliothek\/#website","url":"https:\/\/blog.phzh.ch\/bibliothek\/","name":"biblioPHil","description":"Blog der Bibliothek der PH Z\u00fcrich","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.phzh.ch\/bibliothek\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.phzh.ch\/bibliothek\/#\/schema\/person\/9ac4db73a0ab3878a7f5b8381dd46a26","name":"laradevesa","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.phzh.ch\/bibliothek\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/72078c455ba0352ff2c307bcfb259999?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72078c455ba0352ff2c307bcfb259999?s=96&d=mm&r=g","caption":"laradevesa"},"url":"https:\/\/blog.phzh.ch\/bibliothek\/author\/ldevesa\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/posts\/1552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/users\/1439"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/comments?post=1552"}],"version-history":[{"count":16,"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/posts\/1552\/revisions"}],"predecessor-version":[{"id":1640,"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/posts\/1552\/revisions\/1640"}],"wp:attachment":[{"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/media?parent=1552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/categories?post=1552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.phzh.ch\/bibliothek\/wp-json\/wp\/v2\/tags?post=1552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}